{"id":11855,"date":"2016-08-25T19:50:24","date_gmt":"2016-08-25T19:50:24","guid":{"rendered":"http:\/\/www.visitalanya.com\/wp-content\/uploads\/2016\/08\/Karlama-Vist-Alanya6.jpg"},"modified":"2016-08-25T19:50:24","modified_gmt":"2016-08-25T19:50:24","slug":"karlama-vist-alanya6","status":"inherit","type":"attachment","link":"https:\/\/www.visitalanya.com\/fi\/karlama-vist-alanya6\/","title":{"rendered":"Karlama Vist Alanya6"},"author":1,"comment_status":"open","ping_status":"closed","template":"","meta":{"_mi_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Karlama Vist Alanya6 - Visit Alanya - Alanya is calling<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.visitalanya.com\/fi\/karlama-vist-alanya6\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Karlama Vist Alanya6 - Visit Alanya - Alanya is calling\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.visitalanya.com\/fi\/karlama-vist-alanya6\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Alanya - Alanya is calling\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VisitAlanya\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.visitalanya.com\/wp-content\/uploads\/2016\/08\/Karlama-Vist-Alanya6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@visitalanyacom\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.visitalanya.com\/fi\/karlama-vist-alanya6\/\",\"url\":\"https:\/\/www.visitalanya.com\/fi\/karlama-vist-alanya6\/\",\"name\":\"Karlama Vist Alanya6 - Visit Alanya - Alanya is calling\",\"isPartOf\":{\"@id\":\"https:\/\/www.visitalanya.com\/fi\/#website\"},\"datePublished\":\"2016-08-25T19:50:24+00:00\",\"dateModified\":\"2016-08-25T19:50:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.visitalanya.com\/fi\/karlama-vist-alanya6\/#breadcrumb\"},\"inLanguage\":\"fi\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.visitalanya.com\/fi\/karlama-vist-alanya6\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.visitalanya.com\/fi\/karlama-vist-alanya6\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.visitalanya.com\/fi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Karlama Vist Alanya6\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.visitalanya.com\/fi\/#website\",\"url\":\"https:\/\/www.visitalanya.com\/fi\/\",\"name\":\"Visit Alanya - Alanya is calling\",\"description\":\"Alanya Calling \u2014 Your Mediterranean Escape\",\"publisher\":{\"@id\":\"https:\/\/www.visitalanya.com\/fi\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.visitalanya.com\/fi\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fi\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.visitalanya.com\/fi\/#organization\",\"name\":\"Visit Alanya - Alanya is calling\",\"url\":\"https:\/\/www.visitalanya.com\/fi\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/visit_alanya\/\",\"https:\/\/www.facebook.com\/VisitAlanya\/\",\"https:\/\/twitter.com\/visitalanyacom\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\/\/www.visitalanya.com\/fi\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.visitalanya.com\/wp-content\/uploads\/2015\/09\/logo-smll.png\",\"contentUrl\":\"https:\/\/www.visitalanya.com\/wp-content\/uploads\/2015\/09\/logo-smll.png\",\"width\":160,\"height\":108,\"caption\":\"Visit Alanya - Alanya is calling\"},\"image\":{\"@id\":\"https:\/\/www.visitalanya.com\/fi\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Karlama Vist Alanya6 - Visit Alanya - Alanya is calling","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.visitalanya.com\/fi\/karlama-vist-alanya6\/","og_locale":"fi_FI","og_type":"article","og_title":"Karlama Vist Alanya6 - Visit Alanya - Alanya is calling","og_url":"https:\/\/www.visitalanya.com\/fi\/karlama-vist-alanya6\/","og_site_name":"Visit Alanya - Alanya is calling","article_publisher":"https:\/\/www.facebook.com\/VisitAlanya\/","og_image":[{"width":600,"height":450,"url":"https:\/\/www.visitalanya.com\/wp-content\/uploads\/2016\/08\/Karlama-Vist-Alanya6.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@visitalanyacom","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.visitalanya.com\/fi\/karlama-vist-alanya6\/","url":"https:\/\/www.visitalanya.com\/fi\/karlama-vist-alanya6\/","name":"Karlama Vist Alanya6 - Visit Alanya - Alanya is calling","isPartOf":{"@id":"https:\/\/www.visitalanya.com\/fi\/#website"},"datePublished":"2016-08-25T19:50:24+00:00","dateModified":"2016-08-25T19:50:24+00:00","breadcrumb":{"@id":"https:\/\/www.visitalanya.com\/fi\/karlama-vist-alanya6\/#breadcrumb"},"inLanguage":"fi","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.visitalanya.com\/fi\/karlama-vist-alanya6\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.visitalanya.com\/fi\/karlama-vist-alanya6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.visitalanya.com\/fi\/"},{"@type":"ListItem","position":2,"name":"Karlama Vist Alanya6"}]},{"@type":"WebSite","@id":"https:\/\/www.visitalanya.com\/fi\/#website","url":"https:\/\/www.visitalanya.com\/fi\/","name":"Visit Alanya - Alanya is calling","description":"Alanya Calling \u2014 Your Mediterranean Escape","publisher":{"@id":"https:\/\/www.visitalanya.com\/fi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.visitalanya.com\/fi\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fi"},{"@type":"Organization","@id":"https:\/\/www.visitalanya.com\/fi\/#organization","name":"Visit Alanya - Alanya is calling","url":"https:\/\/www.visitalanya.com\/fi\/","sameAs":["https:\/\/www.instagram.com\/visit_alanya\/","https:\/\/www.facebook.com\/VisitAlanya\/","https:\/\/twitter.com\/visitalanyacom"],"logo":{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/www.visitalanya.com\/fi\/#\/schema\/logo\/image\/","url":"https:\/\/www.visitalanya.com\/wp-content\/uploads\/2015\/09\/logo-smll.png","contentUrl":"https:\/\/www.visitalanya.com\/wp-content\/uploads\/2015\/09\/logo-smll.png","width":160,"height":108,"caption":"Visit Alanya - Alanya is calling"},"image":{"@id":"https:\/\/www.visitalanya.com\/fi\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.visitalanya.com\/wp-content\/uploads\/2016\/08\/Karlama-Vist-Alanya6.jpg' data-rel=\"prettyPhoto[image-11855]\" data-rel=\"prettyPhoto[image-11855]\"><img width=\"300\" height=\"225\" src=\"https:\/\/www.visitalanya.com\/wp-content\/uploads\/2016\/08\/Karlama-Vist-Alanya6-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.visitalanya.com\/wp-content\/uploads\/2016\/08\/Karlama-Vist-Alanya6-300x225.jpg 300w, https:\/\/www.visitalanya.com\/wp-content\/uploads\/2016\/08\/Karlama-Vist-Alanya6.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":600,"height":450,"file":"2016\/08\/Karlama-Vist-Alanya6.jpg","sizes":{"thumbnail":{"file":"Karlama-Vist-Alanya6-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.visitalanya.com\/wp-content\/uploads\/2016\/08\/Karlama-Vist-Alanya6-150x150.jpg"},"medium":{"file":"Karlama-Vist-Alanya6-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/www.visitalanya.com\/wp-content\/uploads\/2016\/08\/Karlama-Vist-Alanya6-300x225.jpg"},"post-thumbnail":{"file":"Karlama-Vist-Alanya6-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.visitalanya.com\/wp-content\/uploads\/2016\/08\/Karlama-Vist-Alanya6-150x150.jpg"},"full":{"file":"Karlama-Vist-Alanya6.jpg","width":600,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/www.visitalanya.com\/wp-content\/uploads\/2016\/08\/Karlama-Vist-Alanya6.jpg"}},"image_meta":{"aperture":"1000000","credit":"","camera":"ev: 20193 $","caption":"","created_timestamp":"0","copyright":"","focal_length":"0.6711412","iso":"80","shutter_speed":"1000000\/0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/www.visitalanya.com\/wp-content\/uploads\/2016\/08\/Karlama-Vist-Alanya6.jpg","_links":{"self":[{"href":"https:\/\/www.visitalanya.com\/fi\/wp-json\/wp\/v2\/media\/11855"}],"collection":[{"href":"https:\/\/www.visitalanya.com\/fi\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.visitalanya.com\/fi\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.visitalanya.com\/fi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.visitalanya.com\/fi\/wp-json\/wp\/v2\/comments?post=11855"}]}}